{"id":606,"date":"2021-03-08T12:05:12","date_gmt":"2021-03-08T12:05:12","guid":{"rendered":"https:\/\/tdnlaw.com\/practice-areas\/"},"modified":"2024-12-30T10:13:53","modified_gmt":"2024-12-30T10:13:53","slug":"practice-areas","status":"publish","type":"page","link":"https:\/\/tdnlaw.com\/es\/practice-areas\/","title":{"rendered":"\u00c1reas de pr\u00e1ctica"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"606\" class=\"elementor elementor-606\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cb7e59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cb7e59\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c18e4fd\" data-id=\"c18e4fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dce9410 elementor-widget elementor-widget-heading\" data-id=\"dce9410\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Carlsbad Family Law Attorneys - Our Practice Areas <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64aa708 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64aa708\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7794e12\" data-id=\"7794e12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-580afa9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"580afa9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fc662da\" data-id=\"fc662da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5312964 elementor-widget elementor-widget-heading\" data-id=\"5312964\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfEn qu\u00e9 podemos ayudarte?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4608e26 elementor-widget elementor-widget-text-editor\" data-id=\"4608e26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our lawyers represent our clients in family law matters throughout San Diego and adjacent counties.<\/p>\n<p>El divorcio y otras disputas de derecho de familia pueden ser muy dif\u00edciles para los adultos y ni\u00f1os involucrados. Nos tomamos un tiempo considerable para guiar a los clientes a trav\u00e9s del proceso explicando la ley y ayudando a los clientes a entender sus derechos. A veces, solo saber que tiene un profesional experimentado que busca el mejor resultado posible en su nombre puede proporcionar un tremendo alivio en tiempos dif\u00edciles.<\/p>\n<p>We have successfully represented many clients in divorce, custody, domestic violence, paternity, and other family law matters for more than 30 years. We deliver a high level of service at a reasonable ra<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2013bc7\" data-id=\"2013bc7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4c976e elementor-widget elementor-widget-image\" data-id=\"d4c976e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-1024x683.jpeg\" class=\"attachment-large size-large wp-image-1540\" alt=\"Divorce and other family law - TDN law - Carlsbad, CA\" srcset=\"https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-1024x683.jpeg 1024w, https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-300x200.jpeg 300w, https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-768x512.jpeg 768w, https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-1536x1024.jpeg 1536w, https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-2048x1365.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bc32a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bc32a0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25e8269\" data-id=\"25e8269\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9da81bf elementor-widget elementor-widget-heading\" data-id=\"9da81bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Brindamos servicios legales experimentados y personalizados en una amplia gama de asuntos de derecho de familia, que incluyen:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-704472e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"704472e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-337aaab\" data-id=\"337aaab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d98153 elementor-widget elementor-widget-toggle\" data-id=\"3d98153\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6451\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6451\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Divorcio<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6451\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6451\"><p class=\"p1\">En California, as\u00ed como en la mayor\u00eda de los estados, el divorcio \"no es culpa\". Por lo tanto, el objetivo es terminar la relaci\u00f3n marital mientras se abordan las cuestiones relacionadas con un divorcio, como la divisi\u00f3n de los bienes comunitarios, la asignaci\u00f3n de deudas comunitarias, la emisi\u00f3n de \u00f3rdenes de manutenci\u00f3n de los hijos menores de edad y las \u00f3rdenes de manutenci\u00f3n del c\u00f3nyuge, si corresponde.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d03b15c\" data-id=\"d03b15c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1723a4 elementor-widget elementor-widget-toggle\" data-id=\"f1723a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2531\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2531\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Paternidad<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2531\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2531\"><p class=\"p1\">Cuando hay hijos menores de edad y los padres no est\u00e1n legalmente casados, el tribunal debe adquirir jurisdicci\u00f3n para emitir una sentencia de paternidad con el fin de formalizar la relaci\u00f3n de los padres con el hijo menor o los hijos. A partir de entonces, el tribunal dictar\u00e1 \u00f3rdenes de manutenci\u00f3n de los hijos, custodia y visita.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-596c890 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"596c890\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63ddfe1\" data-id=\"63ddfe1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8bf7e5 elementor-widget elementor-widget-toggle\" data-id=\"b8bf7e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1931\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1931\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Custodia y visita de los hijos<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1931\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1931\"><p class=\"font_8\">\u00a0Hay dos tipos de custodia de los hijos en California: custodia legal y custodia f\u00edsica. La custodia legal se refiere a qu\u00e9 padre tomar\u00e1 decisiones importantes sobre el bienestar de un ni\u00f1o, como elegir su residencia, proveedor de atenci\u00f3n m\u00e9dica, escuela y proveedor de cuidado infantil. La custodia f\u00edsica se refiere a con qu\u00e9 padre vive el ni\u00f1o la mayor parte del tiempo.<\/p><p class=\"font_8\">Tanto la custodia legal como la f\u00edsica pueden ser conjuntas o \u00fanicas. La custodia legal conjunta permite a los padres compartir los derechos y responsabilidades de tomar decisiones importantes sobre sus hijos. La custodia f\u00edsica conjunta significa que los ni\u00f1os viven con ambos padres, aunque a menudo es demasiado dif\u00edcil dividir el tiempo en una divisi\u00f3n exacta del 50\/50, por lo que los ni\u00f1os pueden vivir m\u00e1s con uno de los padres que con el otro. Si un padre tiene a los hijos m\u00e1s de la mitad del tiempo, puede ser considerado el padre de custodia principal. La custodia exclusiva generalmente significa que los ni\u00f1os viven con uno de los padres la mayor parte del tiempo, pero visitan al otro padre. En muchos casos, el tribunal otorgar\u00e1 la custodia legal conjunta, pero no la custodia f\u00edsica conjunta.<\/p><p class=\"font_8\">Los tribunales de California se centran en el inter\u00e9s superior de los ni\u00f1os al determinar la custodia y las visitas de los hijos. El inter\u00e9s superior de los ni\u00f1os puede requerir un an\u00e1lisis complejo de los problemas que son muy emocionales para todos los miembros de la familia. En general, la corte intenta mantener el \"statu quo\", o las condiciones que exist\u00edan antes del divorcio.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7659607\" data-id=\"7659607\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f96b736 elementor-widget elementor-widget-toggle\" data-id=\"f96b736\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2611\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2611\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Violencia dom\u00e9stica<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2611\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2611\"><p class=\"font_8\">Hay dos tipos de casos de violencia dom\u00e9stica. Hay violencia dom\u00e9stica criminal, seg\u00fan la secci\u00f3n 243(e)(1) del C\u00f3digo Penal. Tambi\u00e9n hay violencia dom\u00e9stica no criminal' seg\u00fan la secci\u00f3n 6203 del C\u00f3digo de Familia (Ley de Prevenci\u00f3n de la Violencia Dom\u00e9stica.<\/p><p class=\"font_8\">La violencia dom\u00e9stica criminal es un delito menor o, a veces, un delito grave, dependiendo de la naturaleza y gravedad de las lesiones. La \"v\u00edctima\" de un acto de violencia dom\u00e9stica debe ser un \"socio \u00edntimo\" de la parte que comete el acto. Una pareja \u00edntima es cualquiera de los siguientes:<\/p><p class=\"font_8\"><span class=\"wixGuard\">\u200b<\/span>Cualquier pareja, independientemente de su orientaci\u00f3n sexual, es decir,<\/p><ol class=\"font_8\"><li><p class=\"font_8\">su c\u00f3nyuge actual o anterior,<\/p><\/li><li><p class=\"font_8\">tu prometido o prometida,<\/p><\/li><li><p class=\"font_8\">un co-padre de tu hijo,<\/p><\/li><li><p class=\"font_8\">una persona que tienes o que has tenido una relaci\u00f3n de citas,<\/p><\/li><li><p class=\"font_8\">una persona con la que vives.<\/p><\/li><\/ol><p class=\"font_8\">La violencia dom\u00e9stica no criminal es un \"abuso\" perpetrado contra cualquiera de las siguientes personas:<\/p><p class=\"font_8\"><span class=\"wixGuard\">\u200b<\/span>(a) Un c\u00f3nyuge o exc\u00f3nyuge.<\/p><p class=\"font_8\">(b) Un cohabitante o ex cohabitante, tal como se define en la Secci\u00f3n 6209.<\/p><p class=\"font_8\">(c) Una persona con la que el demandado est\u00e1 teniendo o ha tenido una relaci\u00f3n de citas o compromiso.<\/p><p class=\"font_8\">d) Una persona con la que el demandado haya tenido un hijo, cuando se aplique la presunci\u00f3n de que el padre var\u00f3n es el padre del hijo del padre femenino en virtud de la Ley Uniforme de Paternidad (Parte 3 (a partir del art\u00edculo 7600) de la Divisi\u00f3n 12).<\/p><p class=\"font_8\">e) Un hijo de una parte o un ni\u00f1o que sea objeto de una acci\u00f3n en virtud de la Ley Uniforme de Paternidad, donde se aplique la presunci\u00f3n de que el padre var\u00f3n es el padre del ni\u00f1o a proteger.<\/p><p class=\"font_8\">(f) Cualquier otra persona relacionada por consanguinidad o afinidad dentro del segundo grado.<\/p><p class=\"font_8\">La palabra \"abuso\" es,<\/p><p class=\"font_8\">(1) Causar o intentar causar lesiones corporales intencional o imprudentemente.<\/p><p class=\"font_8\">(2) Agresi\u00f3n sexual.<\/p><p class=\"font_8\">(3) Poner a una persona en una aprehensi\u00f3n razonable de lesiones corporales graves inminentes a esa persona u otra.<\/p><p class=\"font_8\">(4) Participar en cualquier comportamiento que haya sido o pueda ser ordenado de conformidad con la Secci\u00f3n 6320.<\/p><p class=\"font_8\">El abuso no se limita a la imposici\u00f3n real de lesiones f\u00edsicas o agresi\u00f3n<\/p><p class=\"font_8\">Si se le ha notificado una Orden de Restricci\u00f3n de Violencia Dom\u00e9stica, o es v\u00edctima de Violencia Dom\u00e9stica y requiere la protecci\u00f3n de una Orden de Restricci\u00f3n, podemos ayudarle. No dude en ponerse en contacto con nosotros.<\/p><p class=\"font_8\"><span class=\"wixGuard\">\u200b<\/span>Tambi\u00e9n manejamos otros asuntos de derecho de familia, como acuerdos prenupciales, adopciones de padrastros y tutela de los casos menores. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1b80b8d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b80b8d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-91a224d\" data-id=\"91a224d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af6e9c1 elementor-widget elementor-widget-heading\" data-id=\"af6e9c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tambi\u00e9n nos encargamos de lo siguiente:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9b436ca elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b436ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-10fa1a9\" data-id=\"10fa1a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cba592 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1cba592\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-genderless\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Modificaci\u00f3n posterior a la sentencia<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ef8b3dc\" data-id=\"ef8b3dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a0ffad elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9a0ffad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-genderless\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ejecuci\u00f3n de \u00f3rdenes judiciales<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d028ac2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d028ac2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d946b89\" data-id=\"d946b89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20d9c95 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"20d9c95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-genderless\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Manutenci\u00f3n conyugal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d33051e\" data-id=\"d33051e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-814b0cd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"814b0cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-genderless\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Manutenci\u00f3n de los hijos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9a30307 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a30307\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ed19a0b\" data-id=\"ed19a0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa190f3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fa190f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-genderless\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Divisi\u00f3n de Bienes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-634e0ce\" data-id=\"634e0ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d561d89 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d561d89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-genderless\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Adopci\u00f3n de padrastros<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d0c1ffe elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0c1ffe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-67313a2\" data-id=\"67313a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e4a969 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5e4a969\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-genderless\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tutela de menores<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Carlsbad Family Law Attorneys &#8211; Our Practice Areas How Can We Help You? Our lawyers represent our clients in family law matters throughout San Diego and adjacent counties. Divorce and other family law disputes can be very difficult for the adults and children involved. We take considerable time to guide clients through the process by [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1540,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-606","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Our Practice Areas of Family Law in Carlsbad, California. | Thomas D Nares, APC<\/title>\n<meta name=\"description\" content=\"We take considerable time to guide everyone through the process by explaining the law and helping clients understand their rights.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tdnlaw.com\/es\/practice-areas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our Practice Areas of Family Law in Carlsbad, California.\" \/>\n<meta property=\"og:description\" content=\"We take considerable time to guide everyone through the process by explaining the law and helping clients understand their rights.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tdnlaw.com\/es\/practice-areas\/\" \/>\n<meta property=\"og:site_name\" content=\"Thomas D Nares, APC\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/tdnlaw\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-30T10:13:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Our Practice Areas of Family Law in Carlsbad, California.\" \/>\n<meta name=\"twitter:description\" content=\"We take considerable time to guide everyone through the process by explaining the law and helping clients understand their rights.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg\" \/>\n<meta name=\"twitter:site\" content=\"@nares_tom\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/practice-areas\\\/\",\"url\":\"https:\\\/\\\/tdnlaw.com\\\/practice-areas\\\/\",\"name\":\"Our Practice Areas of Family Law in Carlsbad, California. | Thomas D Nares, APC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/practice-areas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/practice-areas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tdnlaw.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg\",\"datePublished\":\"2021-03-08T12:05:12+00:00\",\"dateModified\":\"2024-12-30T10:13:53+00:00\",\"description\":\"We take considerable time to guide everyone through the process by explaining the law and helping clients understand their rights.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/practice-areas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tdnlaw.com\\\/practice-areas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/practice-areas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tdnlaw.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/tdnlaw.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"Divorce and other family law - TDN law - Carlsbad, CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/practice-areas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tdnlaw.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Practice Areas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/#website\",\"url\":\"https:\\\/\\\/tdnlaw.com\\\/\",\"name\":\"Thomas D Nares, APC\",\"description\":\"Attorney in Carlsbad, California since 1986\",\"publisher\":{\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/#organization\"},\"alternateName\":\"Thomas D. Nares\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tdnlaw.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/#organization\",\"name\":\"Thomas D Nares, APC\",\"alternateName\":\"Thomas D. Nares\",\"url\":\"https:\\\/\\\/tdnlaw.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tdnlaw.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/tdnlaw-logo.webp\",\"contentUrl\":\"https:\\\/\\\/tdnlaw.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/tdnlaw-logo.webp\",\"width\":1069,\"height\":821,\"caption\":\"Thomas D Nares, APC\"},\"image\":{\"@id\":\"https:\\\/\\\/tdnlaw.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/tdnlaw\",\"https:\\\/\\\/x.com\\\/nares_tom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our Practice Areas of Family Law in Carlsbad, California. | Thomas D Nares, APC","description":"We take considerable time to guide everyone through the process by explaining the law and helping clients understand their rights.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tdnlaw.com\/es\/practice-areas\/","og_locale":"es_MX","og_type":"article","og_title":"Our Practice Areas of Family Law in Carlsbad, California.","og_description":"We take considerable time to guide everyone through the process by explaining the law and helping clients understand their rights.","og_url":"https:\/\/tdnlaw.com\/es\/practice-areas\/","og_site_name":"Thomas D Nares, APC","article_publisher":"http:\/\/facebook.com\/tdnlaw","article_modified_time":"2024-12-30T10:13:53+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Our Practice Areas of Family Law in Carlsbad, California.","twitter_description":"We take considerable time to guide everyone through the process by explaining the law and helping clients understand their rights.","twitter_image":"https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg","twitter_site":"@nares_tom","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tdnlaw.com\/practice-areas\/","url":"https:\/\/tdnlaw.com\/practice-areas\/","name":"Our Practice Areas of Family Law in Carlsbad, California. | Thomas D Nares, APC","isPartOf":{"@id":"https:\/\/tdnlaw.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tdnlaw.com\/practice-areas\/#primaryimage"},"image":{"@id":"https:\/\/tdnlaw.com\/practice-areas\/#primaryimage"},"thumbnailUrl":"https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg","datePublished":"2021-03-08T12:05:12+00:00","dateModified":"2024-12-30T10:13:53+00:00","description":"We take considerable time to guide everyone through the process by explaining the law and helping clients understand their rights.","breadcrumb":{"@id":"https:\/\/tdnlaw.com\/practice-areas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tdnlaw.com\/practice-areas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tdnlaw.com\/practice-areas\/#primaryimage","url":"https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg","contentUrl":"https:\/\/tdnlaw.com\/wp-content\/uploads\/2022\/01\/gabe-pierce-htEGTleSCZk-unsplash-scaled.jpeg","width":2560,"height":1707,"caption":"Divorce and other family law - TDN law - Carlsbad, CA"},{"@type":"BreadcrumbList","@id":"https:\/\/tdnlaw.com\/practice-areas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tdnlaw.com\/"},{"@type":"ListItem","position":2,"name":"Practice Areas"}]},{"@type":"WebSite","@id":"https:\/\/tdnlaw.com\/#website","url":"https:\/\/tdnlaw.com\/","name":"Thomas D Nares, APC","description":"Attorney in Carlsbad, California since 1986","publisher":{"@id":"https:\/\/tdnlaw.com\/#organization"},"alternateName":"Thomas D. Nares","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tdnlaw.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tdnlaw.com\/#organization","name":"Thomas D Nares, APC","alternateName":"Thomas D. Nares","url":"https:\/\/tdnlaw.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tdnlaw.com\/#\/schema\/logo\/image\/","url":"https:\/\/tdnlaw.com\/wp-content\/uploads\/2024\/07\/tdnlaw-logo.webp","contentUrl":"https:\/\/tdnlaw.com\/wp-content\/uploads\/2024\/07\/tdnlaw-logo.webp","width":1069,"height":821,"caption":"Thomas D Nares, APC"},"image":{"@id":"https:\/\/tdnlaw.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/tdnlaw","https:\/\/x.com\/nares_tom"]}]}},"_links":{"self":[{"href":"https:\/\/tdnlaw.com\/es\/wp-json\/wp\/v2\/pages\/606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tdnlaw.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tdnlaw.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tdnlaw.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tdnlaw.com\/es\/wp-json\/wp\/v2\/comments?post=606"}],"version-history":[{"count":12,"href":"https:\/\/tdnlaw.com\/es\/wp-json\/wp\/v2\/pages\/606\/revisions"}],"predecessor-version":[{"id":3067,"href":"https:\/\/tdnlaw.com\/es\/wp-json\/wp\/v2\/pages\/606\/revisions\/3067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tdnlaw.com\/es\/wp-json\/wp\/v2\/media\/1540"}],"wp:attachment":[{"href":"https:\/\/tdnlaw.com\/es\/wp-json\/wp\/v2\/media?parent=606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}